






{"id":27596,"date":"2025-05-28T09:13:07","date_gmt":"2025-05-28T02:13:07","guid":{"rendered":"https:\/\/edutrade.vn\/?p=27596"},"modified":"2025-05-28T09:13:07","modified_gmt":"2025-05-28T02:13:07","slug":"gia-thep-hom-nay-28-5-quang-sat-tiep-tuc-giam-thi-tru","status":"publish","type":"post","link":"https:\/\/edutrade.vn\/en\/gia-thep-hom-nay-28-5-quang-sat-tiep-tuc-giam-thi-tru\/","title":{"rendered":"Gi\u00e1 th\u00e9p h\u00f4m nay 28\/5: Qu\u1eb7ng s\u1eaft ti\u1ebfp t\u1ee5c gi\u1ea3m, th\u1ecb tr\u01b0\u1eddng th\u00e9p ch\u1eefng l\u1ea1i"},"content":{"rendered":"<p style=\"text-align: justify\" data-start=\"278\" data-end=\"497\"><a href=\"https:\/\/steelonline.vn\/price-list#google_vignette\"><strong data-start=\"278\" data-end=\"303\">Gi\u00e1 th\u00e9p h\u00f4m nay 28\/5<\/strong><\/a> ghi nh\u1eadn xu h\u01b0\u1edbng \u0111i xu\u1ed1ng tr\u00ean th\u1ecb tr\u01b0\u1eddng qu\u1ed1c t\u1ebf do lo ng\u1ea1i v\u1ec1 kh\u1ea3 n\u0103ng c\u1eaft gi\u1ea3m s\u1ea3n l\u01b0\u1ee3ng t\u1ea1i Trung Qu\u1ed1c. Trong khi \u0111\u00f3, th\u1ecb tr\u01b0\u1eddng trong n\u01b0\u1edbc v\u1eabn gi\u1eef nguy\u00ean m\u1ee9c gi\u00e1 so v\u1edbi c\u00e1c phi\u00ean g\u1ea7n \u0111\u00e2y.<\/p>\n<h2 style=\"text-align: justify\" data-start=\"504\" data-end=\"564\">Gi\u00e1 th\u00e9p th\u1ebf gi\u1edbi gi\u1ea3m do \u00e1p l\u1ef1c t\u1eeb th\u1ecb tr\u01b0\u1eddng Trung Qu\u1ed1c<\/h2>\n<p style=\"text-align: justify\" data-start=\"566\" data-end=\"792\">Tr\u00ean s\u00e0n giao d\u1ecbch Th\u01b0\u1ee3ng H\u1ea3i (SHFE), <strong data-start=\"604\" data-end=\"629\">gi\u00e1 th\u00e9p h\u00f4m nay 28\/5<\/strong> ti\u1ebfp t\u1ee5c \u0111i xu\u1ed1ng, \u0111\u00e1nh d\u1ea5u phi\u00ean gi\u1ea3m th\u1ee9 ba li\u00ean ti\u1ebfp. Nguy\u00ean nh\u00e2n \u0111\u1ebfn t\u1eeb nh\u1eefng \u0111\u1ed3n \u0111o\u00e1n v\u1ec1 vi\u1ec7c Trung Qu\u1ed1c s\u1ebd c\u1eaft gi\u1ea3m s\u1ea3n l\u01b0\u1ee3ng th\u00e9p th\u00f4 \u0111\u1ec3 ki\u1ec3m so\u00e1t d\u01b0 cung.<\/p>\n<h3 style=\"text-align: justify\" data-start=\"794\" data-end=\"838\">B\u1ea3ng gi\u00e1 th\u00e9p tr\u00ean s\u00e0n Th\u01b0\u1ee3ng H\u1ea3i (SHFE)<\/h3>\n<div class=\"_tableContainer_16hzy_1\" style=\"text-align: justify\">\n<div class=\"_tableWrapper_16hzy_14 group flex w-fit flex-col-reverse\">\n<table class=\"w-fit min-w-(--thread-content-width)\" data-start=\"840\" data-end=\"1328\">\n<thead data-start=\"840\" data-end=\"918\">\n<tr data-start=\"840\" data-end=\"918\">\n<th data-start=\"840\" data-end=\"862\" data-col-size=\"sm\">M\u1eb7t h\u00e0ng<\/th>\n<th data-start=\"862\" data-end=\"876\" data-col-size=\"sm\">K\u1ef3 h\u1ea1n giao<\/th>\n<th data-start=\"876\" data-end=\"892\" data-col-size=\"sm\">Gi\u00e1 (CNY\/t\u1ea5n)<\/th>\n<th data-start=\"892\" data-end=\"904\" data-col-size=\"sm\">T\u0103ng\/Gi\u1ea3m<\/th>\n<th data-start=\"904\" data-end=\"918\" data-col-size=\"sm\">% thay \u0111\u1ed5i<\/th>\n<\/tr>\n<\/thead>\n<tbody data-start=\"1001\" data-end=\"1328\">\n<tr data-start=\"1001\" data-end=\"1082\">\n<td data-start=\"1001\" data-end=\"1023\" data-col-size=\"sm\">Th\u00e9p c\u00e2y (Rebar)<\/td>\n<td data-col-size=\"sm\" data-start=\"1023\" data-end=\"1037\">Th\u00e1ng 10\/25<\/td>\n<td data-col-size=\"sm\" data-start=\"1037\" data-end=\"1053\">2.970<\/td>\n<td data-col-size=\"sm\" data-start=\"1053\" data-end=\"1066\">-17<\/td>\n<td data-col-size=\"sm\" data-start=\"1066\" data-end=\"1082\">-1,23%<\/td>\n<\/tr>\n<tr data-start=\"1083\" data-end=\"1164\">\n<td data-start=\"1083\" data-end=\"1105\" data-col-size=\"sm\">Th\u00e9p cu\u1ed9n c\u00e1n n\u00f3ng<\/td>\n<td data-start=\"1105\" data-end=\"1119\" data-col-size=\"sm\">&#8211;<\/td>\n<td data-start=\"1119\" data-end=\"1135\" data-col-size=\"sm\">&#8211;<\/td>\n<td data-start=\"1135\" data-end=\"1148\" data-col-size=\"sm\">&#8211;<\/td>\n<td data-start=\"1148\" data-end=\"1164\" data-col-size=\"sm\">-1,33%<\/td>\n<\/tr>\n<tr data-start=\"1165\" data-end=\"1246\">\n<td data-start=\"1165\" data-end=\"1187\" data-col-size=\"sm\">Th\u00e9p d\u00e2y (SWRcv1)<\/td>\n<td data-start=\"1187\" data-end=\"1201\" data-col-size=\"sm\">&#8211;<\/td>\n<td data-start=\"1201\" data-end=\"1217\" data-col-size=\"sm\">&#8211;<\/td>\n<td data-start=\"1217\" data-end=\"1230\" data-col-size=\"sm\">&#8211;<\/td>\n<td data-start=\"1230\" data-end=\"1246\" data-col-size=\"sm\">-0,34%<\/td>\n<\/tr>\n<tr data-start=\"1247\" data-end=\"1328\">\n<td data-start=\"1247\" data-end=\"1269\" data-col-size=\"sm\">Th\u00e9p kh\u00f4ng g\u1ec9<\/td>\n<td data-start=\"1269\" data-end=\"1283\" data-col-size=\"sm\">&#8211;<\/td>\n<td data-start=\"1283\" data-end=\"1299\" data-col-size=\"sm\">&#8211;<\/td>\n<td data-start=\"1299\" data-end=\"1312\" data-col-size=\"sm\">&#8211;<\/td>\n<td data-start=\"1312\" data-end=\"1328\" data-col-size=\"sm\">-0,19%<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<div class=\"sticky end-(--thread-content-margin) h-0 self-end select-none\">\n<div class=\"absolute end-0 flex items-end\"><span style=\"color: #212121;font-size: 1.953em\">Gi\u00e1 qu\u1eb7ng s\u1eaft ti\u1ebfp t\u1ee5c lao d\u1ed1c phi\u00ean th\u1ee9 ba li\u00ean ti\u1ebfp<\/span><\/div>\n<\/div>\n<\/div>\n<\/div>\n<p style=\"text-align: justify\" data-start=\"1393\" data-end=\"1507\">Gi\u00e1 qu\u1eb7ng s\u1eaft \u0111ang ch\u1ecbu \u00e1p l\u1ef1c l\u1edbn khi th\u1ecb tr\u01b0\u1eddng lo ng\u1ea1i v\u1ec1 nhu c\u1ea7u y\u1ebfu do Trung Qu\u1ed1c c\u00f3 th\u1ec3 si\u1ebft s\u1ea3n l\u01b0\u1ee3ng th\u00e9p.<\/p>\n<h3 style=\"text-align: justify\" data-start=\"1509\" data-end=\"1559\">B\u1ea3ng gi\u00e1 qu\u1eb7ng s\u1eaft t\u1ea1i Trung Qu\u1ed1c v\u00e0 Singapore<\/h3>\n<div class=\"_tableContainer_16hzy_1\" style=\"text-align: justify\">\n<div class=\"_tableWrapper_16hzy_14 group flex w-fit flex-col-reverse\">\n<table class=\"w-fit min-w-(--thread-content-width)\" data-start=\"1561\" data-end=\"1851\">\n<thead data-start=\"1561\" data-end=\"1632\">\n<tr data-start=\"1561\" data-end=\"1632\">\n<th data-start=\"1561\" data-end=\"1577\" data-col-size=\"sm\">S\u00e0n giao d\u1ecbch<\/th>\n<th data-start=\"1577\" data-end=\"1590\" data-col-size=\"sm\">K\u1ef3 h\u1ea1n<\/th>\n<th data-start=\"1590\" data-end=\"1601\" data-col-size=\"sm\">Gi\u00e1<\/th>\n<th data-start=\"1601\" data-end=\"1613\" data-col-size=\"sm\">T\u0103ng\/Gi\u1ea3m<\/th>\n<th data-start=\"1613\" data-end=\"1632\" data-col-size=\"sm\">Quy \u0111\u1ed5i USD\/t\u1ea5n<\/th>\n<\/tr>\n<\/thead>\n<tbody data-start=\"1706\" data-end=\"1851\">\n<tr data-start=\"1706\" data-end=\"1778\">\n<td data-start=\"1706\" data-end=\"1722\" data-col-size=\"sm\">DCE Trung Qu\u1ed1c<\/td>\n<td data-start=\"1722\" data-end=\"1735\" data-col-size=\"sm\">Th\u00e1ng 9\/25<\/td>\n<td data-start=\"1735\" data-end=\"1746\" data-col-size=\"sm\">698,5 CNY<\/td>\n<td data-start=\"1746\" data-end=\"1758\" data-col-size=\"sm\">-1,76%<\/td>\n<td data-start=\"1758\" data-end=\"1778\" data-col-size=\"sm\">~97,16 USD<\/td>\n<\/tr>\n<tr data-start=\"1779\" data-end=\"1851\">\n<td data-start=\"1779\" data-end=\"1795\" data-col-size=\"sm\">Singapore<\/td>\n<td data-start=\"1795\" data-end=\"1808\" data-col-size=\"sm\">Th\u00e1ng 6\/25<\/td>\n<td data-start=\"1808\" data-end=\"1819\" data-col-size=\"sm\">&#8211;<\/td>\n<td data-start=\"1819\" data-end=\"1831\" data-col-size=\"sm\">-0,95%<\/td>\n<td data-start=\"1831\" data-end=\"1851\" data-col-size=\"sm\">96,15 USD<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<div class=\"sticky end-(--thread-content-margin) h-0 self-end select-none\">\n<div class=\"absolute end-0 flex items-end\">Ph\u00e1t bi\u1ec3u t\u1ea1i s\u1ef1 ki\u1ec7n ng\u00e0nh \u1edf Singapore, \u00f4ng <strong data-start=\"1898\" data-end=\"1912\">Tang Zujun<\/strong> \u2013 Ph\u00f3 Ch\u1ee7 t\u1ecbch Hi\u1ec7p h\u1ed9i S\u1eaft Th\u00e9p Trung Qu\u1ed1c \u2013 cho bi\u1ebft n\u01b0\u1edbc n\u00e0y \u0111ang n\u1ed7 l\u1ef1c ki\u1ec3m so\u00e1t s\u1ef1 m\u1edf r\u1ed9ng c\u1ee7a ng\u00e0nh \u0111\u1ec3 gi\u1ea3i quy\u1ebft t\u00ecnh tr\u1ea1ng d\u01b0 cung k\u00e9o d\u00e0i.<\/div>\n<\/div>\n<\/div>\n<\/div>\n<h2 style=\"text-align: justify\" data-start=\"2068\" data-end=\"2129\">Gi\u00e1 c\u00e1c nguy\u00ean li\u1ec7u s\u1ea3n xu\u1ea5t th\u00e9p kh\u00e1c c\u0169ng \u0111\u1ed3ng lo\u1ea1t gi\u1ea3m<\/h2>\n<p style=\"text-align: justify\" data-start=\"2131\" data-end=\"2265\">B\u00ean c\u1ea1nh qu\u1eb7ng s\u1eaft, c\u00e1c nguy\u00ean li\u1ec7u quan tr\u1ecdng kh\u00e1c trong s\u1ea3n xu\u1ea5t th\u00e9p nh\u01b0 than luy\u1ec7n kim v\u00e0 than c\u1ed1c c\u0169ng ghi nh\u1eadn xu h\u01b0\u1edbng suy y\u1ebfu.<\/p>\n<h3 style=\"text-align: justify\" data-start=\"2267\" data-end=\"2313\">B\u1ea3ng gi\u00e1 nguy\u00ean li\u1ec7u s\u1ea3n xu\u1ea5t th\u00e9p t\u1ea1i DCE<\/h3>\n<div class=\"_tableContainer_16hzy_1\" style=\"text-align: justify\">\n<div class=\"_tableWrapper_16hzy_14 group flex w-fit flex-col-reverse\">\n<table class=\"w-fit min-w-(--thread-content-width)\" data-start=\"2315\" data-end=\"2501\">\n<thead data-start=\"2315\" data-end=\"2360\">\n<tr data-start=\"2315\" data-end=\"2360\">\n<th data-start=\"2315\" data-end=\"2333\" data-col-size=\"sm\">Nguy\u00ean li\u1ec7u<\/th>\n<th data-start=\"2333\" data-end=\"2348\" data-col-size=\"sm\">M\u00e3 giao d\u1ecbch<\/th>\n<th data-start=\"2348\" data-end=\"2360\" data-col-size=\"sm\">M\u1ee9c gi\u1ea3m<\/th>\n<\/tr>\n<\/thead>\n<tbody data-start=\"2408\" data-end=\"2501\">\n<tr data-start=\"2408\" data-end=\"2454\">\n<td data-start=\"2408\" data-end=\"2427\" data-col-size=\"sm\">Than luy\u1ec7n kim<\/td>\n<td data-start=\"2427\" data-end=\"2442\" data-col-size=\"sm\">&#8211;<\/td>\n<td data-start=\"2442\" data-end=\"2454\" data-col-size=\"sm\">-0,12%<\/td>\n<\/tr>\n<tr data-start=\"2455\" data-end=\"2501\">\n<td data-start=\"2455\" data-end=\"2474\" data-col-size=\"sm\">Than c\u1ed1c<\/td>\n<td data-start=\"2474\" data-end=\"2489\" data-col-size=\"sm\">DCJcv1<\/td>\n<td data-start=\"2489\" data-end=\"2501\" data-col-size=\"sm\">-0,94%<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<div class=\"sticky end-(--thread-content-margin) h-0 self-end select-none\">\n<div class=\"absolute end-0 flex items-end\"><span style=\"color: #212121;font-size: 1.953em\">T\u00edn hi\u1ec7u ph\u1ee5c h\u1ed3i t\u1eeb kinh t\u1ebf Trung Qu\u1ed1c<\/span><\/div>\n<\/div>\n<\/div>\n<\/div>\n<p style=\"text-align: justify\" data-start=\"2552\" data-end=\"2805\">D\u00f9 gi\u00e1 th\u00e9p s\u1ee5t gi\u1ea3m, m\u1ed9t \u0111i\u1ec3m s\u00e1ng l\u00e0 l\u1ee3i nhu\u1eadn c\u00f4ng nghi\u1ec7p t\u1ea1i Trung Qu\u1ed1c trong th\u00e1ng 4 t\u0103ng tr\u01b0\u1edfng tr\u1edf l\u1ea1i. \u0110i\u1ec1u n\u00e0y ph\u1ea7n n\u00e0o cho th\u1ea5y kh\u1ea3 n\u0103ng ph\u1ee5c h\u1ed3i c\u1ee7a n\u1ec1n kinh t\u1ebf l\u1edbn th\u1ee9 hai th\u1ebf gi\u1edbi, b\u1ea5t ch\u1ea5p c\u0103ng th\u1eb3ng th\u01b0\u01a1ng m\u1ea1i v\u00e0 \u00e1p l\u1ef1c gi\u1ea3m ph\u00e1t n\u1ed9i \u0111\u1ecba.<\/p>\n<h2 style=\"text-align: justify\" data-start=\"2812\" data-end=\"2867\">Gi\u00e1 th\u00e9p trong n\u01b0\u1edbc h\u00f4m nay 28\/5: Gi\u1eef nguy\u00ean \u1ed5n \u0111\u1ecbnh<\/h2>\n<p style=\"text-align: justify\" data-start=\"2869\" data-end=\"2998\">T\u1ea1i Vi\u1ec7t Nam, <strong data-start=\"2883\" data-end=\"2908\">gi\u00e1 th\u00e9p h\u00f4m nay 28\/5<\/strong> kh\u00f4ng c\u00f3 s\u1ef1 \u0111i\u1ec1u ch\u1ec9nh m\u1edbi. C\u00e1c th\u01b0\u01a1ng hi\u1ec7u l\u1edbn ti\u1ebfp t\u1ee5c gi\u1eef m\u1ee9c gi\u00e1 \u1ed5n \u0111\u1ecbnh t\u1eeb \u0111\u1ea7u tu\u1ea7n.<\/p>\n<h3 style=\"text-align: justify\" data-start=\"3000\" data-end=\"3056\">B\u1ea3ng gi\u00e1 th\u00e9p trong n\u01b0\u1edbc theo khu v\u1ef1c (\u0110VT: \u0111\u1ed3ng\/kg)<\/h3>\n<h4 style=\"text-align: justify\" data-start=\"3058\" data-end=\"3071\">Mi\u1ec1n B\u1eafc<\/h4>\n<div class=\"_tableContainer_16hzy_1\" style=\"text-align: justify\">\n<div class=\"_tableWrapper_16hzy_14 group flex w-fit flex-col-reverse\">\n<table class=\"w-fit min-w-(--thread-content-width)\" data-start=\"3073\" data-end=\"3672\">\n<thead data-start=\"3073\" data-end=\"3122\">\n<tr data-start=\"3073\" data-end=\"3122\">\n<th data-start=\"3073\" data-end=\"3089\" data-col-size=\"sm\">Th\u01b0\u01a1ng hi\u1ec7u<\/th>\n<th data-start=\"3089\" data-end=\"3111\" data-col-size=\"sm\">Lo\u1ea1i th\u00e9p<\/th>\n<th data-start=\"3111\" data-end=\"3122\" data-col-size=\"sm\">Gi\u00e1 b\u00e1n<\/th>\n<\/tr>\n<\/thead>\n<tbody data-start=\"3173\" data-end=\"3672\">\n<tr data-start=\"3173\" data-end=\"3222\">\n<td data-start=\"3173\" data-end=\"3189\" data-col-size=\"sm\">H\u00f2a Ph\u00e1t<\/td>\n<td data-start=\"3189\" data-end=\"3211\" data-col-size=\"sm\">CB240<\/td>\n<td data-start=\"3211\" data-end=\"3222\" data-col-size=\"sm\">13.790<\/td>\n<\/tr>\n<tr data-start=\"3223\" data-end=\"3272\">\n<td data-start=\"3223\" data-end=\"3239\" data-col-size=\"sm\"><\/td>\n<td data-start=\"3239\" data-end=\"3261\" data-col-size=\"sm\">D10 CB300<\/td>\n<td data-start=\"3261\" data-end=\"3272\" data-col-size=\"sm\">13.740<\/td>\n<\/tr>\n<tr data-start=\"3273\" data-end=\"3322\">\n<td data-start=\"3273\" data-end=\"3289\" data-col-size=\"sm\">Vi\u1ec7t \u00dd<\/td>\n<td data-start=\"3289\" data-end=\"3311\" data-col-size=\"sm\">CB240<\/td>\n<td data-start=\"3311\" data-end=\"3322\" data-col-size=\"sm\">13.890<\/td>\n<\/tr>\n<tr data-start=\"3323\" data-end=\"3372\">\n<td data-start=\"3323\" data-end=\"3339\" data-col-size=\"sm\"><\/td>\n<td data-start=\"3339\" data-end=\"3361\" data-col-size=\"sm\">D10 CB300<\/td>\n<td data-start=\"3361\" data-end=\"3372\" data-col-size=\"sm\">13.640<\/td>\n<\/tr>\n<tr data-start=\"3373\" data-end=\"3422\">\n<td data-start=\"3373\" data-end=\"3389\" data-col-size=\"sm\">Vi\u1ec7t \u0110\u1ee9c<\/td>\n<td data-start=\"3389\" data-end=\"3411\" data-col-size=\"sm\">CB240<\/td>\n<td data-start=\"3411\" data-end=\"3422\" data-col-size=\"sm\">13.600<\/td>\n<\/tr>\n<tr data-start=\"3423\" data-end=\"3472\">\n<td data-start=\"3423\" data-end=\"3439\" data-col-size=\"sm\"><\/td>\n<td data-start=\"3439\" data-end=\"3461\" data-col-size=\"sm\">D10 CB300<\/td>\n<td data-start=\"3461\" data-end=\"3472\" data-col-size=\"sm\">13.350<\/td>\n<\/tr>\n<tr data-start=\"3473\" data-end=\"3522\">\n<td data-start=\"3473\" data-end=\"3489\" data-col-size=\"sm\">Vi\u1ec7t Sing<\/td>\n<td data-start=\"3489\" data-end=\"3511\" data-col-size=\"sm\">CB240<\/td>\n<td data-start=\"3511\" data-end=\"3522\" data-col-size=\"sm\">13.690<\/td>\n<\/tr>\n<tr data-start=\"3523\" data-end=\"3572\">\n<td data-start=\"3523\" data-end=\"3539\" data-col-size=\"sm\"><\/td>\n<td data-start=\"3539\" data-end=\"3561\" data-col-size=\"sm\">D10 CB300<\/td>\n<td data-start=\"3561\" data-end=\"3572\" data-col-size=\"sm\">13.580<\/td>\n<\/tr>\n<tr data-start=\"3573\" data-end=\"3622\">\n<td data-start=\"3573\" data-end=\"3589\" data-col-size=\"sm\">VAS<\/td>\n<td data-start=\"3589\" data-end=\"3611\" data-col-size=\"sm\">CB240<\/td>\n<td data-start=\"3611\" data-end=\"3622\" data-col-size=\"sm\">13.740<\/td>\n<\/tr>\n<tr data-start=\"3623\" data-end=\"3672\">\n<td data-start=\"3623\" data-end=\"3639\" data-col-size=\"sm\"><\/td>\n<td data-start=\"3639\" data-end=\"3661\" data-col-size=\"sm\">D10 CB300<\/td>\n<td data-start=\"3661\" data-end=\"3672\" data-col-size=\"sm\">13.740<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<div class=\"sticky end-(--thread-content-margin) h-0 self-end select-none\">\n<div class=\"absolute end-0 flex items-end\"><span style=\"color: #212121;font-size: 1.25em\">Mi\u1ec1n Trung<\/span><\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"_tableContainer_16hzy_1\" style=\"text-align: justify\">\n<div class=\"_tableWrapper_16hzy_14 group flex w-fit flex-col-reverse\">\n<table class=\"w-fit min-w-(--thread-content-width)\" data-start=\"3691\" data-end=\"4090\">\n<thead data-start=\"3691\" data-end=\"3740\">\n<tr data-start=\"3691\" data-end=\"3740\">\n<th data-start=\"3691\" data-end=\"3707\" data-col-size=\"sm\">Th\u01b0\u01a1ng hi\u1ec7u<\/th>\n<th data-start=\"3707\" data-end=\"3729\" data-col-size=\"sm\">Lo\u1ea1i th\u00e9p<\/th>\n<th data-start=\"3729\" data-end=\"3740\" data-col-size=\"sm\">Gi\u00e1 b\u00e1n<\/th>\n<\/tr>\n<\/thead>\n<tbody data-start=\"3791\" data-end=\"4090\">\n<tr data-start=\"3791\" data-end=\"3840\">\n<td data-start=\"3791\" data-end=\"3807\" data-col-size=\"sm\">H\u00f2a Ph\u00e1t<\/td>\n<td data-start=\"3807\" data-end=\"3829\" data-col-size=\"sm\">CB240<\/td>\n<td data-start=\"3829\" data-end=\"3840\" data-col-size=\"sm\">13.840<\/td>\n<\/tr>\n<tr data-start=\"3841\" data-end=\"3890\">\n<td data-start=\"3841\" data-end=\"3857\" data-col-size=\"sm\"><\/td>\n<td data-start=\"3857\" data-end=\"3879\" data-col-size=\"sm\">D10 CB300<\/td>\n<td data-start=\"3879\" data-end=\"3890\" data-col-size=\"sm\">13.790<\/td>\n<\/tr>\n<tr data-start=\"3891\" data-end=\"3940\">\n<td data-start=\"3891\" data-end=\"3907\" data-col-size=\"sm\">Vi\u1ec7t \u0110\u1ee9c<\/td>\n<td data-start=\"3907\" data-end=\"3929\" data-col-size=\"sm\">CB240<\/td>\n<td data-start=\"3929\" data-end=\"3940\" data-col-size=\"sm\">14.050<\/td>\n<\/tr>\n<tr data-start=\"3941\" data-end=\"3990\">\n<td data-start=\"3941\" data-end=\"3957\" data-col-size=\"sm\"><\/td>\n<td data-start=\"3957\" data-end=\"3979\" data-col-size=\"sm\">D10 CB300<\/td>\n<td data-start=\"3979\" data-end=\"3990\" data-col-size=\"sm\">14.000<\/td>\n<\/tr>\n<tr data-start=\"3991\" data-end=\"4040\">\n<td data-start=\"3991\" data-end=\"4007\" data-col-size=\"sm\">VAS<\/td>\n<td data-start=\"4007\" data-end=\"4029\" data-col-size=\"sm\">CB240<\/td>\n<td data-start=\"4029\" data-end=\"4040\" data-col-size=\"sm\">13.740<\/td>\n<\/tr>\n<tr data-start=\"4041\" data-end=\"4090\">\n<td data-start=\"4041\" data-end=\"4057\" data-col-size=\"sm\"><\/td>\n<td data-start=\"4057\" data-end=\"4079\" data-col-size=\"sm\">D10 CB300<\/td>\n<td data-start=\"4079\" data-end=\"4090\" data-col-size=\"sm\">13.790<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<div class=\"sticky end-(--thread-content-margin) h-0 self-end select-none\">\n<div class=\"absolute end-0 flex items-end\"><span style=\"color: #212121;font-size: 1.25em\">Mi\u1ec1n Nam<\/span><\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"_tableContainer_16hzy_1\" style=\"text-align: justify\">\n<div class=\"_tableWrapper_16hzy_14 group flex w-fit flex-col-reverse\">\n<table class=\"w-fit min-w-(--thread-content-width)\" data-start=\"4107\" data-end=\"4406\">\n<thead data-start=\"4107\" data-end=\"4156\">\n<tr data-start=\"4107\" data-end=\"4156\">\n<th data-start=\"4107\" data-end=\"4123\" data-col-size=\"sm\">Th\u01b0\u01a1ng hi\u1ec7u<\/th>\n<th data-start=\"4123\" data-end=\"4145\" data-col-size=\"sm\">Lo\u1ea1i th\u00e9p<\/th>\n<th data-start=\"4145\" data-end=\"4156\" data-col-size=\"sm\">Gi\u00e1 b\u00e1n<\/th>\n<\/tr>\n<\/thead>\n<tbody data-start=\"4207\" data-end=\"4406\">\n<tr data-start=\"4207\" data-end=\"4256\">\n<td data-start=\"4207\" data-end=\"4223\" data-col-size=\"sm\">H\u00f2a Ph\u00e1t<\/td>\n<td data-start=\"4223\" data-end=\"4245\" data-col-size=\"sm\">CB240<\/td>\n<td data-start=\"4245\" data-end=\"4256\" data-col-size=\"sm\">13.790<\/td>\n<\/tr>\n<tr data-start=\"4257\" data-end=\"4306\">\n<td data-start=\"4257\" data-end=\"4273\" data-col-size=\"sm\"><\/td>\n<td data-start=\"4273\" data-end=\"4295\" data-col-size=\"sm\">D10 CB300<\/td>\n<td data-start=\"4295\" data-end=\"4306\" data-col-size=\"sm\">13.740<\/td>\n<\/tr>\n<tr data-start=\"4307\" data-end=\"4356\">\n<td data-start=\"4307\" data-end=\"4323\" data-col-size=\"sm\">VAS<\/td>\n<td data-start=\"4323\" data-end=\"4345\" data-col-size=\"sm\">CB240<\/td>\n<td data-start=\"4345\" data-end=\"4356\" data-col-size=\"sm\">13.740<\/td>\n<\/tr>\n<tr data-start=\"4357\" data-end=\"4406\">\n<td data-start=\"4357\" data-end=\"4373\" data-col-size=\"sm\"><\/td>\n<td data-start=\"4373\" data-end=\"4395\" data-col-size=\"sm\">D10 CB300<\/td>\n<td data-start=\"4395\" data-end=\"4406\" data-col-size=\"sm\">13.840<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<div class=\"sticky end-(--thread-content-margin) h-0 self-end select-none\">\n<div class=\"absolute end-0 flex items-end\"><span style=\"color: #212121;font-size: 1.953em\">Nh\u1eadn \u0111\u1ecbnh v\u00e0 d\u1ef1 b\u00e1o th\u1ecb tr\u01b0\u1eddng th\u00e9p<\/span><\/div>\n<\/div>\n<\/div>\n<\/div>\n<p style=\"text-align: justify\" data-start=\"4453\" data-end=\"4695\">M\u1eb7c d\u00f9 <strong data-start=\"4460\" data-end=\"4485\">gi\u00e1 th\u00e9p h\u00f4m nay 28\/5<\/strong> ghi nh\u1eadn xu h\u01b0\u1edbng gi\u1ea3m tr\u00ean th\u1ecb tr\u01b0\u1eddng qu\u1ed1c t\u1ebf, th\u1ecb tr\u01b0\u1eddng Vi\u1ec7t Nam v\u1eabn gi\u1eef \u1ed5n \u0111\u1ecbnh. Tuy nhi\u00ean, n\u1ebfu gi\u00e1 nguy\u00ean li\u1ec7u ti\u1ebfp t\u1ee5c suy y\u1ebfu, c\u00e1c doanh nghi\u1ec7p th\u00e9p n\u1ed9i \u0111\u1ecba c\u00f3 th\u1ec3 xem x\u00e9t \u0111i\u1ec1u ch\u1ec9nh trong nh\u1eefng k\u1ef3 t\u1edbi.<\/p>\n<p style=\"text-align: justify\" data-start=\"4697\" data-end=\"4729\">C\u00e1c y\u1ebfu t\u1ed1 c\u1ea7n theo d\u00f5i bao g\u1ed3m:<\/p>\n<ul style=\"text-align: justify\" data-start=\"4731\" data-end=\"4880\">\n<li data-start=\"4731\" data-end=\"4778\">\n<p data-start=\"4733\" data-end=\"4778\">Ch\u00ednh s\u00e1ch c\u1eaft gi\u1ea3m s\u1ea3n l\u01b0\u1ee3ng c\u1ee7a Trung Qu\u1ed1c.<\/p>\n<\/li>\n<li data-start=\"4779\" data-end=\"4813\">\n<p data-start=\"4781\" data-end=\"4813\">Bi\u1ebfn \u0111\u1ed9ng gi\u00e1 qu\u1eb7ng s\u1eaft v\u00e0 than.<\/p>\n<\/li>\n<li data-start=\"4814\" data-end=\"4880\">\n<p data-start=\"4816\" data-end=\"4880\">T\u00ecnh h\u00ecnh kinh t\u1ebf v\u00e0 nhu c\u1ea7u x\u00e2y d\u1ef1ng t\u1ea1i th\u1ecb tr\u01b0\u1eddng trong n\u01b0\u1edbc.<\/p>\n<\/li>\n<\/ul>\n<h2 style=\"text-align: justify\" data-start=\"4887\" data-end=\"4898\">K\u1ebft lu\u1eadn<\/h2>\n<p style=\"text-align: justify\" data-start=\"4900\" data-end=\"5253\"><strong data-start=\"4900\" data-end=\"4925\">Gi\u00e1 th\u00e9p h\u00f4m nay 28\/5<\/strong> cho th\u1ea5y nh\u1eefng d\u1ea5u hi\u1ec7u suy gi\u1ea3m do \u00e1p l\u1ef1c t\u1eeb Trung Qu\u1ed1c v\u00e0 s\u1ef1 ch\u1eefng l\u1ea1i c\u1ee7a th\u1ecb tr\u01b0\u1eddng qu\u1eb7ng s\u1eaft. Tuy nhi\u00ean, nh\u1edd l\u1ee3i nhu\u1eadn c\u00f4ng nghi\u1ec7p ph\u1ee5c h\u1ed3i v\u00e0 gi\u00e1 trong n\u01b0\u1edbc \u1ed5n \u0111\u1ecbnh, th\u1ecb tr\u01b0\u1eddng th\u00e9p v\u1eabn \u0111ang trong tr\u1ea1ng th\u00e1i ki\u1ec3m so\u00e1t. Trong th\u1eddi gian t\u1edbi, nh\u00e0 \u0111\u1ea7u t\u01b0 c\u1ea7n theo s\u00e1t di\u1ec5n bi\u1ebfn t\u1eeb th\u1ecb tr\u01b0\u1eddng qu\u1ed1c t\u1ebf \u0111\u1ec3 c\u00f3 quy\u1ebft \u0111\u1ecbnh ph\u00f9 h\u1ee3p.<\/p>\n<p data-start=\"4251\" data-end=\"4583\"><strong>Tin Hot:<\/strong><\/p>\n<ul>\n<li data-start=\"4251\" data-end=\"4583\"><a href=\"https:\/\/edutrade.vn\/en\/gia-vang-hom-nay-28-5-2025-lao-doc-phien-thu-ba-lie\/\">Gi\u00e1 v\u00e0ng h\u00f4m nay<\/a><\/li>\n<li data-start=\"4251\" data-end=\"4583\"><a href=\"https:\/\/edutrade.vn\/en\/gia-bac-hom-nay-28-5-2025-dong-usd-manh-len-bac-mat\/\">Gi\u00e1 b\u1ea1c h\u00f4m nay<\/a><\/li>\n<li data-start=\"4251\" data-end=\"4583\"><a href=\"https:\/\/edutrade.vn\/en\/gia-ca-phe-hom-nay-28-5-2025-bat-tang-manh-tro-lai-thi\/\">Gi\u00e1 c\u00e0 ph\u00ea h\u00f4m nay<\/a><\/li>\n<li data-start=\"4251\" data-end=\"4583\"><a href=\"https:\/\/edutrade.vn\/en\/gia-xang-dau-hom-nay-28-05-2025-giam-manh-do-lo-ngai\/\">Gi\u00e1 x\u0103ng d\u1ea7u h\u00f4m nay<\/a><\/li>\n<li data-start=\"4251\" data-end=\"4583\"><a href=\"https:\/\/edutrade.vn\/en\/gia-cao-su-hom-nay-28-5-thi-truong-phuc-hoi-tai-sin\/\">Gi\u00e1 cao su h\u00f4m nay<\/a><\/li>\n<\/ul>\n<p style=\"text-align: right\"><strong>\u0110\u1ee9c Huy<\/strong><\/p>","protected":false},"excerpt":{"rendered":"<p>Gi\u00e1 th\u00e9p h\u00f4m nay 28\/5 ghi nh\u1eadn xu h\u01b0\u1edbng \u0111i xu\u1ed1ng tr\u00ean th\u1ecb tr\u01b0\u1eddng qu\u1ed1c t\u1ebf do lo ng\u1ea1i v\u1ec1 kh\u1ea3 n\u0103ng c\u1eaft gi\u1ea3m s\u1ea3n l\u01b0\u1ee3ng t\u1ea1i Trung Qu\u1ed1c. Trong khi \u0111\u00f3, th\u1ecb tr\u01b0\u1eddng trong n\u01b0\u1edbc v\u1eabn gi\u1eef nguy\u00ean m\u1ee9c gi\u00e1 so v\u1edbi c\u00e1c phi\u00ean g\u1ea7n \u0111\u00e2y. Gi\u00e1 th\u00e9p th\u1ebf gi\u1edbi gi\u1ea3m do \u00e1p l\u1ef1c [&hellip;]<\/p>","protected":false},"author":63,"featured_media":26354,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"jnews-multi-image_gallery":[],"jnews_single_post":{"subtitle":"","format":"standard"},"jnews_primary_category":[],"footnotes":""},"categories":[149],"tags":[],"class_list":["post-27596","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tin-tuc"],"acf":[],"_links":{"self":[{"href":"https:\/\/edutrade.vn\/en\/wp-json\/wp\/v2\/posts\/27596","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/edutrade.vn\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/edutrade.vn\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/edutrade.vn\/en\/wp-json\/wp\/v2\/users\/63"}],"replies":[{"embeddable":true,"href":"https:\/\/edutrade.vn\/en\/wp-json\/wp\/v2\/comments?post=27596"}],"version-history":[{"count":0,"href":"https:\/\/edutrade.vn\/en\/wp-json\/wp\/v2\/posts\/27596\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/edutrade.vn\/en\/wp-json\/wp\/v2\/media\/26354"}],"wp:attachment":[{"href":"https:\/\/edutrade.vn\/en\/wp-json\/wp\/v2\/media?parent=27596"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/edutrade.vn\/en\/wp-json\/wp\/v2\/categories?post=27596"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/edutrade.vn\/en\/wp-json\/wp\/v2\/tags?post=27596"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}